{"id":28115,"date":"2023-07-06T12:08:24","date_gmt":"2023-07-06T10:08:24","guid":{"rendered":"https:\/\/pro-lithium.com\/boutique\/uncategorized\/roller-team-livingstone-go-12v-150ah\/"},"modified":"2023-07-06T12:08:24","modified_gmt":"2023-07-06T10:08:24","slug":"roller-team-livingstone-go-12v-150ah","status":"publish","type":"product","link":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/","title":{"rendered":"Roller Team Livingstone Go 12V 150Ah"},"content":{"rendered":"<h4>Roller Team Livingstone Go 12V 150Ah<\/h4>\n<p><u>F\u00fcr Einzelpersonen:<\/u><\/p>\n<p><strong>Ersetzen<\/strong> eine Standardbatterie mit Lithiumbatterie erh\u00f6ht die elektrische Autonomie des Wohnmobils. <strong>Fix<\/strong> mit einer Lithiumbatterie k\u00f6nnen Sie die erheblichen Kosten im Vergleich zum Kauf einer neuen Lithiumbatterie f\u00fcr ein Wohnmobil senken. <strong>Standardaustausch<\/strong> dies ist nur m\u00f6glich, wenn es sich bei der zur\u00fcckgegebenen Batterie um eine Lithiumbatterie handelt. Dadurch werden die Kosten f\u00fcr den Austausch durch eine neue Lithiumbatterie reduziert, die den Anforderungen des Wohnmobils entspricht.. <strong>Recyceln<\/strong> Eine Campingbatterie, die Sie bei uns anfordern, erm\u00f6glicht Ihnen einen \u00f6kologischen Ansatz, aber auch eine erhebliche finanzielle Entsch\u00e4digung.<\/p>\n<p><u>F\u00fcr Profis:<\/u><\/p>\n<p><strong>Montage<\/strong> von Lithiumbatterien in Frankreich <strong>Partnerschaft<\/strong> Verteilung <strong>Anpassung<\/strong> Batterien auf Anfrage <strong>Reparieren<\/strong> f\u00fcr Lithiumbatterien <strong>\u00dcberholung<\/strong> von Lithiumbatterien <strong>Wiederaufnahme<\/strong> von Lithiumbatterien zum Recycling<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lithiumbatterien f\u00fcr Wohnmobile k\u00f6nnen zur Speicherung von Strom zur Deckung des Strombedarfs verwendet werden.<\/p>\n<p>Sie erm\u00f6glichen beispielsweise die Speicherung von Energie aus f\u00fcr Wohnmobile geeigneten Solarpanels.<\/p>\n<p>F\u00fcr Privatpersonen bietet und montiert Pro Lithium in Frankreich Lithiumbatterien mit einer Garantie von mehreren Jahren.<\/p>\n<p>Als Profi f\u00fcr Wohnmobile stellt Pro Lithium in Frankreich Lithiumbatterien her, die an Ihre Bed\u00fcrfnisse angepasst sind.<\/p>\n<p>Die Auswahl an Wohnmobilen kann mit Lithiumbatterien ausgestattet sein, um das Gewicht des Fahrzeugs zu reduzieren, aber auch um die elektrische Autonomie des Fahrzeugs zu erh\u00f6hen.<\/p>\n","protected":false},"featured_media":18428,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[1187,635],"product_tag":[],"class_list":["post-28115","product","type-product","status-publish","has-post-thumbnail","product_cat-roller-team-de","product_cat-wohnwagen","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roller Team Livingstone Go 12V 150Ah - Pro Lithium Lithiumbatterie-Spezialist<\/title>\n<meta name=\"description\" content=\"Roller Team Livingstone Go 12V 150Ah Ersetzen \u2013 Reparieren \u2013 Standardaustausch \u2013 Recycling \u2013 F\u00fcr Privatpersonen und Wohnmobilprofis\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roller Team Livingstone Go 12V 150Ah\" \/>\n<meta property=\"og:description\" content=\"Roller Team Livingstone Go 12V 150Ah Ersetzen \u2013 Reparieren \u2013 Standardaustausch \u2013 Recycling \u2013 F\u00fcr Privatpersonen und Wohnmobilprofis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Lithium Lithiumbatterie-Spezialist\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/100063769014463\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pro-lithium.com\/wp-content\/uploads\/2023\/07\/Roller-Livingstone-Go.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/\",\"url\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/\",\"name\":\"Roller Team Livingstone Go 12V 150Ah - Pro Lithium Lithiumbatterie-Spezialist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pro-lithium.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Roller-Livingstone-Go.png\",\"datePublished\":\"2023-07-06T10:08:24+00:00\",\"description\":\"Roller Team Livingstone Go 12V 150Ah Ersetzen \u2013 Reparieren \u2013 Standardaustausch \u2013 Recycling \u2013 F\u00fcr Privatpersonen und Wohnmobilprofis\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pro-lithium.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Roller-Livingstone-Go.png\",\"contentUrl\":\"https:\\\/\\\/pro-lithium.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Roller-Livingstone-Go.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/pro-lithium.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Roller Team Livingstone Go 12V 150Ah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/\",\"name\":\"Pro Lithium Sp\u00e9cialiste Batteries Lithium\",\"description\":\"Pro Lithium Spezialist f\u00fcr Lithiumbatterien \u2013 Design, Herstellung, Wartung, Recycling von Lithiumbatterien.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/#organization\",\"name\":\"Pro Lithium\",\"alternateName\":\"Li-Akku\",\"url\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/100063769014463\"],\"description\":\"Anlage zum Recycling von Lithiumbatterien. Verkauf von LFP NIMH NCM Akkuzellen 18650 21700 26650 26700\",\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pro-lithium.com\\\/de\\\/shop\\\/wohnwagen\\\/roller-team-de\\\/roller-team-livingstone-go-12v-150ah\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/pro-lithium.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/prolithium-logo.png\",\"contentUrl\":\"https:\\\/\\\/pro-lithium.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/prolithium-logo.png\",\"width\":465,\"height\":117,\"caption\":\"Pro Lithium\"}]}<\/script>\n<meta property=\"product:price:currency\" content=\"USD\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roller Team Livingstone Go 12V 150Ah - Pro Lithium Lithiumbatterie-Spezialist","description":"Roller Team Livingstone Go 12V 150Ah Ersetzen \u2013 Reparieren \u2013 Standardaustausch \u2013 Recycling \u2013 F\u00fcr Privatpersonen und Wohnmobilprofis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/","og_locale":"de_DE","og_type":"article","og_title":"Roller Team Livingstone Go 12V 150Ah","og_description":"Roller Team Livingstone Go 12V 150Ah Ersetzen \u2013 Reparieren \u2013 Standardaustausch \u2013 Recycling \u2013 F\u00fcr Privatpersonen und Wohnmobilprofis","og_url":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/","og_site_name":"Pro Lithium Lithiumbatterie-Spezialist","article_publisher":"https:\/\/www.facebook.com\/100063769014463","og_image":[{"width":600,"height":600,"url":"https:\/\/pro-lithium.com\/wp-content\/uploads\/2023\/07\/Roller-Livingstone-Go.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/","url":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/","name":"Roller Team Livingstone Go 12V 150Ah - Pro Lithium Lithiumbatterie-Spezialist","isPartOf":{"@id":"https:\/\/pro-lithium.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/#primaryimage"},"image":{"@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/#primaryimage"},"thumbnailUrl":"https:\/\/pro-lithium.com\/wp-content\/uploads\/2023\/07\/Roller-Livingstone-Go.png","datePublished":"2023-07-06T10:08:24+00:00","description":"Roller Team Livingstone Go 12V 150Ah Ersetzen \u2013 Reparieren \u2013 Standardaustausch \u2013 Recycling \u2013 F\u00fcr Privatpersonen und Wohnmobilprofis","breadcrumb":{"@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/#primaryimage","url":"https:\/\/pro-lithium.com\/wp-content\/uploads\/2023\/07\/Roller-Livingstone-Go.png","contentUrl":"https:\/\/pro-lithium.com\/wp-content\/uploads\/2023\/07\/Roller-Livingstone-Go.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pro-lithium.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/pro-lithium.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Roller Team Livingstone Go 12V 150Ah"}]},{"@type":"WebSite","@id":"https:\/\/pro-lithium.com\/de\/#website","url":"https:\/\/pro-lithium.com\/de\/","name":"Pro Lithium Sp\u00e9cialiste Batteries Lithium","description":"Pro Lithium Spezialist f\u00fcr Lithiumbatterien \u2013 Design, Herstellung, Wartung, Recycling von Lithiumbatterien.","publisher":{"@id":"https:\/\/pro-lithium.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pro-lithium.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/pro-lithium.com\/de\/#organization","name":"Pro Lithium","alternateName":"Li-Akku","url":"https:\/\/pro-lithium.com\/de\/","logo":{"@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/#local-main-organization-logo"},"image":{"@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/100063769014463"],"description":"Anlage zum Recycling von Lithiumbatterien. Verkauf von LFP NIMH NCM Akkuzellen 18650 21700 26650 26700","telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pro-lithium.com\/de\/shop\/wohnwagen\/roller-team-de\/roller-team-livingstone-go-12v-150ah\/#local-main-organization-logo","url":"https:\/\/pro-lithium.com\/wp-content\/uploads\/2022\/10\/prolithium-logo.png","contentUrl":"https:\/\/pro-lithium.com\/wp-content\/uploads\/2022\/10\/prolithium-logo.png","width":465,"height":117,"caption":"Pro Lithium"}]},"product_price_currency":"USD","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/pro-lithium.com\/de\/wp-json\/wp\/v2\/product\/28115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pro-lithium.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pro-lithium.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pro-lithium.com\/de\/wp-json\/wp\/v2\/media\/18428"}],"wp:attachment":[{"href":"https:\/\/pro-lithium.com\/de\/wp-json\/wp\/v2\/media?parent=28115"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pro-lithium.com\/de\/wp-json\/wp\/v2\/product_brand?post=28115"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pro-lithium.com\/de\/wp-json\/wp\/v2\/product_cat?post=28115"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pro-lithium.com\/de\/wp-json\/wp\/v2\/product_tag?post=28115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}